{"id":10631,"date":"2014-03-19T04:21:13","date_gmt":"2014-03-19T04:21:13","guid":{"rendered":"http:\/\/www.antaiji.org\/?p=10631"},"modified":"2021-05-13T03:00:53","modified_gmt":"2021-05-13T03:00:53","slug":"%e4%bd%9c%e5%8b%99%e9%96%8b%e5%a7%8b%e3%80%812014%e5%b9%b43%e6%9c%8819%e6%97%a5","status":"publish","type":"post","link":"http:\/\/www.antaiji.org\/de\/%e4%bd%9c%e5%8b%99%e9%96%8b%e5%a7%8b%e3%80%812014%e5%b9%b43%e6%9c%8819%e6%97%a5\/","title":{"rendered":"Erste Arbeiten, 19. Maerz 2014"},"content":{"rendered":"<p>Die ersten Arbeiten in diesem Jahr begannen gestern.<br \/>\nDa die Starsse noch nicht passierbar ist,und es auch noch zu frueh ist, um die Felder zu pfluegen, haben wir erst einmal damit begonnen, die Papierfenster zu wechseln.<br \/>\nUnd in der Kueche haben wir einen brandneunen Holzherd. Bei der Gelgenheit haben wir es natuerlich nicht versaeumt, auch den Schornstein oderntlich zu putzen.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/s3ojtUdzT8M\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/34bfmHi-TDA\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/9x0Je276VLY\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Die ersten Arbeiten in diesem Jahr begannen gestern. Da die Starsse noch nicht passierbar ist,und es auch noch zu frueh ist, um die Felder zu pfluegen, haben wir erst einmal damit begonnen, die Papierfenster zu wechseln. Und in der Kueche haben wir einen brandneunen Holzherd. Bei der Gelgenheit haben wir es natuerlich nicht versaeumt, auch &#8230; <a title=\"Erste Arbeiten, 19. Maerz 2014\" class=\"read-more\" href=\"http:\/\/www.antaiji.org\/de\/%e4%bd%9c%e5%8b%99%e9%96%8b%e5%a7%8b%e3%80%812014%e5%b9%b43%e6%9c%8819%e6%97%a5\/\" aria-label=\"Mehr Informationen \u00fcber Erste Arbeiten, 19. Maerz 2014\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[29,78],"tags":[],"class_list":["post-10631","post","type-post","status-publish","format-standard","hentry","category-blog","category-video"],"_links":{"self":[{"href":"http:\/\/www.antaiji.org\/de\/wp-json\/wp\/v2\/posts\/10631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.antaiji.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.antaiji.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.antaiji.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.antaiji.org\/de\/wp-json\/wp\/v2\/comments?post=10631"}],"version-history":[{"count":2,"href":"http:\/\/www.antaiji.org\/de\/wp-json\/wp\/v2\/posts\/10631\/revisions"}],"predecessor-version":[{"id":19017,"href":"http:\/\/www.antaiji.org\/de\/wp-json\/wp\/v2\/posts\/10631\/revisions\/19017"}],"wp:attachment":[{"href":"http:\/\/www.antaiji.org\/de\/wp-json\/wp\/v2\/media?parent=10631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.antaiji.org\/de\/wp-json\/wp\/v2\/categories?post=10631"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.antaiji.org\/de\/wp-json\/wp\/v2\/tags?post=10631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}